{"id":651,"date":"2023-03-28T00:02:32","date_gmt":"2023-03-27T22:02:32","guid":{"rendered":"https:\/\/www.new.patacca.nl\/event\/mahler-4-wir-geniessen-die-himmlischen-freuden\/"},"modified":"2023-03-28T00:02:32","modified_gmt":"2023-03-27T22:02:32","slug":"mahler-4-wir-geniessen-die-himmlischen-freuden","status":"publish","type":"tribe_events","link":"https:\/\/www.patacca.nl\/en\/event\/mahler-4-wir-geniessen-die-himmlischen-freuden\/","title":{"rendered":"Mahler 4 &#8216;Wir geniessen die Himmlischen Freuden&#8217;"},"content":{"rendered":"<p>20.00 uur Maastricht olv Michale ReinWunderhorn Ensemble<\/p>\n","protected":false},"excerpt":{"rendered":"<p>20.00 uur Maastricht olv Michale ReinWunderhorn Ensemble<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","meta":{"ngg_post_thumbnail":0,"_EventAllDay":false,"_EventTimezone":"Europe\/Amsterdam","_EventStartDate":"2017-06-27 00:00:00","_EventEndDate":"2017-06-27 00:00:00","_EventStartDateUTC":"2017-06-26 22:00:00","_EventEndDateUTC":"2017-06-26 22:00:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-651","tribe_events","type-tribe_events","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mahler 4 &#039;Wir geniessen die Himmlischen Freuden&#039; - Claudia Patacca - Sopraan<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.patacca.nl\/en\/event\/mahler-4-wir-geniessen-die-himmlischen-freuden\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mahler 4 &#039;Wir geniessen die Himmlischen Freuden&#039; - Claudia Patacca - Sopraan\" \/>\n<meta property=\"og:description\" content=\"20.00 uur Maastricht olv Michale ReinWunderhorn Ensemble\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.patacca.nl\/en\/event\/mahler-4-wir-geniessen-die-himmlischen-freuden\/\" \/>\n<meta property=\"og:site_name\" content=\"Claudia Patacca - Sopraan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.patacca.nl\\\/en\\\/event\\\/mahler-4-wir-geniessen-die-himmlischen-freuden\\\/\",\"url\":\"https:\\\/\\\/www.patacca.nl\\\/en\\\/event\\\/mahler-4-wir-geniessen-die-himmlischen-freuden\\\/\",\"name\":\"Mahler 4 'Wir geniessen die Himmlischen Freuden' - Claudia Patacca - Sopraan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.patacca.nl\\\/en\\\/#website\"},\"datePublished\":\"2023-03-27T22:02:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.patacca.nl\\\/en\\\/event\\\/mahler-4-wir-geniessen-die-himmlischen-freuden\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.patacca.nl\\\/en\\\/event\\\/mahler-4-wir-geniessen-die-himmlischen-freuden\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.patacca.nl\\\/en\\\/event\\\/mahler-4-wir-geniessen-die-himmlischen-freuden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.patacca.nl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/www.patacca.nl\\\/en\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mahler 4 &#8216;Wir geniessen die Himmlischen Freuden&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.patacca.nl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.patacca.nl\\\/en\\\/\",\"name\":\"Claudia Patacca - Sopraan\",\"description\":\"Music is the food of love...           Music was my first love...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.patacca.nl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mahler 4 'Wir geniessen die Himmlischen Freuden' - Claudia Patacca - Sopraan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.patacca.nl\/en\/event\/mahler-4-wir-geniessen-die-himmlischen-freuden\/","og_locale":"en_US","og_type":"article","og_title":"Mahler 4 'Wir geniessen die Himmlischen Freuden' - Claudia Patacca - Sopraan","og_description":"20.00 uur Maastricht olv Michale ReinWunderhorn Ensemble","og_url":"https:\/\/www.patacca.nl\/en\/event\/mahler-4-wir-geniessen-die-himmlischen-freuden\/","og_site_name":"Claudia Patacca - Sopraan","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.patacca.nl\/en\/event\/mahler-4-wir-geniessen-die-himmlischen-freuden\/","url":"https:\/\/www.patacca.nl\/en\/event\/mahler-4-wir-geniessen-die-himmlischen-freuden\/","name":"Mahler 4 'Wir geniessen die Himmlischen Freuden' - Claudia Patacca - Sopraan","isPartOf":{"@id":"https:\/\/www.patacca.nl\/en\/#website"},"datePublished":"2023-03-27T22:02:32+00:00","breadcrumb":{"@id":"https:\/\/www.patacca.nl\/en\/event\/mahler-4-wir-geniessen-die-himmlischen-freuden\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.patacca.nl\/en\/event\/mahler-4-wir-geniessen-die-himmlischen-freuden\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.patacca.nl\/en\/event\/mahler-4-wir-geniessen-die-himmlischen-freuden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.patacca.nl\/en\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/www.patacca.nl\/en\/events\/"},{"@type":"ListItem","position":3,"name":"Mahler 4 &#8216;Wir geniessen die Himmlischen Freuden&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/www.patacca.nl\/en\/#website","url":"https:\/\/www.patacca.nl\/en\/","name":"Claudia Patacca - Sopraan","description":"Music is the food of love...           Music was my first love...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.patacca.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.patacca.nl\/en\/wp-json\/wp\/v2\/tribe_events\/651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.patacca.nl\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.patacca.nl\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.patacca.nl\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.patacca.nl\/en\/wp-json\/wp\/v2\/tribe_events\/651\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.patacca.nl\/en\/wp-json\/wp\/v2\/media?parent=651"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.patacca.nl\/en\/wp-json\/wp\/v2\/tags?post=651"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.patacca.nl\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}